{"id":185172,"date":"2016-12-23T00:00:00","date_gmt":"2016-12-22T23:00:00","guid":{"rendered":"https:\/\/www.alfauna.ch.vasco.sui-inter.net\/shop\/unkategorisiert\/puur-heustick-gemuese-nager\/"},"modified":"2026-03-23T04:48:00","modified_gmt":"2026-03-23T03:48:00","slug":"puur-heurolle-sellerie-200gr","status":"publish","type":"product","link":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/","title":{"rendered":"PUUR Heurolle Sellerie"},"content":{"rendered":"<p>Rohfaser tr\u00e4gt zur ausgezeichneten Verdauung bei<br \/>\nDie ideale Aktivit\u00e4t f\u00fcr Ihr geliebtes Haustier<br \/>\nDieser verantwortungsbewusste Snack unterst\u00fctzt die Gesundheit insgesamt<br \/>\nOhne k\u00fcnstliche Konservierungsstoffe, Farbstoffe oder Aromastoffe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rohfaser tr\u00e4gt zur ausgezeichneten Verdauung bei Die ideale Aktivit\u00e4t f\u00fcr Ihr geliebtes Haustier Dieser verantwortungsbewusste Snack unterst\u00fctzt die Gesundheit insgesamt Ohne k\u00fcnstliche Konservierungsstoffe, Farbstoffe oder Aromastoffe<\/p>\n","protected":false},"featured_media":562236,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[3593,2605],"product_tag":[],"class_list":{"0":"post-185172","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-futter-nagetiere-kaninchen","7":"product_cat-nagetiere-kaninchen","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PUUR Heurolle Sellerie - alfauna AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PUUR Heurolle Sellerie - alfauna AG\" \/>\n<meta property=\"og:description\" content=\"Rohfaser tr\u00e4gt zur ausgezeichneten Verdauung bei Die ideale Aktivit\u00e4t f\u00fcr Ihr geliebtes Haustier Dieser verantwortungsbewusste Snack unterst\u00fctzt die Gesundheit insgesamt Ohne k\u00fcnstliche Konservierungsstoffe, Farbstoffe oder Aromastoffe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/\" \/>\n<meta property=\"og:site_name\" content=\"alfauna AG\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T03:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/1845_gr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/\",\"url\":\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/\",\"name\":\"PUUR Heurolle Sellerie - alfauna AG\",\"isPartOf\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stage.alfauna.ch\/wp-content\/uploads\/2024\/04\/1845_gr.jpg\",\"datePublished\":\"2016-12-22T23:00:00+00:00\",\"dateModified\":\"2026-03-23T03:48:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#primaryimage\",\"url\":\"https:\/\/stage.alfauna.ch\/wp-content\/uploads\/2024\/04\/1845_gr.jpg\",\"contentUrl\":\"https:\/\/stage.alfauna.ch\/wp-content\/uploads\/2024\/04\/1845_gr.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.alfauna.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.alfauna.ch\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PUUR Heurolle Sellerie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#website\",\"url\":\"https:\/\/www.alfauna.ch\/de\/\",\"name\":\"alfauna AG\",\"description\":\"Tierbedarf f\u00fcr Fachh\u00e4ndler\",\"publisher\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.alfauna.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#organization\",\"name\":\"alfauna AG\",\"url\":\"https:\/\/www.alfauna.ch\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png\",\"contentUrl\":\"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png\",\"width\":230,\"height\":123,\"caption\":\"alfauna AG\"},\"image\":{\"@id\":\"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PUUR Heurolle Sellerie - alfauna AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/","og_locale":"de_DE","og_type":"article","og_title":"PUUR Heurolle Sellerie - alfauna AG","og_description":"Rohfaser tr\u00e4gt zur ausgezeichneten Verdauung bei Die ideale Aktivit\u00e4t f\u00fcr Ihr geliebtes Haustier Dieser verantwortungsbewusste Snack unterst\u00fctzt die Gesundheit insgesamt Ohne k\u00fcnstliche Konservierungsstoffe, Farbstoffe oder Aromastoffe","og_url":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/","og_site_name":"alfauna AG","article_modified_time":"2026-03-23T03:48:00+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/2024\/04\/1845_gr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/","url":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/","name":"PUUR Heurolle Sellerie - alfauna AG","isPartOf":{"@id":"https:\/\/www.alfauna.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#primaryimage"},"image":{"@id":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#primaryimage"},"thumbnailUrl":"https:\/\/stage.alfauna.ch\/wp-content\/uploads\/2024\/04\/1845_gr.jpg","datePublished":"2016-12-22T23:00:00+00:00","dateModified":"2026-03-23T03:48:00+00:00","breadcrumb":{"@id":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#primaryimage","url":"https:\/\/stage.alfauna.ch\/wp-content\/uploads\/2024\/04\/1845_gr.jpg","contentUrl":"https:\/\/stage.alfauna.ch\/wp-content\/uploads\/2024\/04\/1845_gr.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/stage.alfauna.ch\/de\/shop\/nagetiere-kaninchen\/futter-nagetiere-kaninchen\/puur-heurolle-sellerie-200gr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.alfauna.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.alfauna.ch\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"PUUR Heurolle Sellerie"}]},{"@type":"WebSite","@id":"https:\/\/www.alfauna.ch\/de\/#website","url":"https:\/\/www.alfauna.ch\/de\/","name":"alfauna AG","description":"Tierbedarf f\u00fcr Fachh\u00e4ndler","publisher":{"@id":"https:\/\/www.alfauna.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alfauna.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.alfauna.ch\/de\/#organization","name":"alfauna AG","url":"https:\/\/www.alfauna.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png","contentUrl":"https:\/\/www.alfauna.ch\/wp-content\/uploads\/logo_alfauna_230px.png","width":230,"height":123,"caption":"alfauna AG"},"image":{"@id":"https:\/\/www.alfauna.ch\/de\/#\/schema\/logo\/image\/"}}]}},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"7":4.85},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/stage.alfauna.ch\/de\/wp-json\/wp\/v2\/product\/185172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.alfauna.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stage.alfauna.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stage.alfauna.ch\/de\/wp-json\/wp\/v2\/media\/562236"}],"wp:attachment":[{"href":"https:\/\/stage.alfauna.ch\/de\/wp-json\/wp\/v2\/media?parent=185172"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stage.alfauna.ch\/de\/wp-json\/wp\/v2\/product_brand?post=185172"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stage.alfauna.ch\/de\/wp-json\/wp\/v2\/product_cat?post=185172"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stage.alfauna.ch\/de\/wp-json\/wp\/v2\/product_tag?post=185172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}